{"id":6880,"date":"2024-07-31T18:21:28","date_gmt":"2024-07-31T18:21:28","guid":{"rendered":"https:\/\/latamreports.com\/br\/?p=6880"},"modified":"2024-07-31T18:21:30","modified_gmt":"2024-07-31T18:21:30","slug":"governo-estabelece-novas-regras-para-jogos-de-azar-online","status":"publish","type":"post","link":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/","title":{"rendered":"Governo estabelece novas regras para jogos de azar online"},"content":{"rendered":"\n<p>O Minist\u00e9rio da Fazenda publicou, nesta quarta-feira, 31, uma portaria no Di\u00e1rio Oficial que define crit\u00e9rios t\u00e9cnicos para <a href=\"https:\/\/latamreports.com\/br\/governo-avalia-liberacao-do-jogo-do-tigrinho-no-brasil\/\">jogos de azar online<\/a>, como o popular \u201cJogo do Tigrinho\u201d. Esse tipo de jogo ganhou destaque ap\u00f3s casos de endividamento de jogadores e divulga\u00e7\u00e3o massiva nas redes sociais por influenciadores digitais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Novas regras e categoriza\u00e7\u00f5es<\/h2>\n\n\n\n<p>De acordo com a portaria, jogos de azar s\u00e3o aqueles em que \u201co resultado \u00e9 determinado pelo desfecho de evento futuro aleat\u00f3rio, a partir de um gerador rand\u00f4mico de n\u00fameros, s\u00edmbolos, figuras ou objetos definido no sistema de regras\u201d. N\u00e3o est\u00e3o inclu\u00eddas nesta categoria as plataformas de apostas esportivas, classificadas como \u201cjogos multiapostador\u201d, onde \u201cas a\u00e7\u00f5es do apostador ou resultados por ele obtidos sejam influenciados pelo resultado ou a\u00e7\u00e3o de qualquer outro apostador\u201d.<\/p>\n\n\n\n<p>A nova regulamenta\u00e7\u00e3o permite o funcionamento desses jogos no pa\u00eds, desde que sigam as regras estipuladas. Os respons\u00e1veis devem solicitar autoriza\u00e7\u00e3o ao Minist\u00e9rio da Fazenda, e os jogos ser\u00e3o analisados por certificadores autorizados para verificar o cumprimento das normas. At\u00e9 o momento, cinco empresas fizeram o requerimento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Requisitos para opera\u00e7\u00e3o e prote\u00e7\u00e3o ao jjogador<\/h2>\n\n\n\n<p>Os jogos devem informar aos usu\u00e1rios, no momento da aposta, o fator de multiplica\u00e7\u00e3o para cada Real apostado, definindo claramente o valor que o <a href=\"https:\/\/latamreports.com\/br\/lives-do-jogo-do-tigrinho-inundam-canais-do-youtube-com-conteudo-enganoso\/\">apostador <\/a>receber\u00e1 em caso de vit\u00f3ria. Antes de finalizar a aposta, o jogo deve apresentar as tabelas de pagamento, detalhando todas as possibilidades de ganho. O valor do pr\u00eamio n\u00e3o pode ser alterado ap\u00f3s a realiza\u00e7\u00e3o da aposta.<\/p>\n\n\n\n<p>Al\u00e9m disso, as artes gr\u00e1ficas dos jogos devem explicar de maneira clara como o jogador pode vencer, incluindo a ordem e a quantidade de s\u00edmbolos necess\u00e1rios para a vit\u00f3ria. A sess\u00e3o de aposta deve ser encerrada ap\u00f3s 30 minutos de inatividade do jogador. A portaria tamb\u00e9m pro\u00edbe a oferta de jogos online de apostas em ambientes f\u00edsicos por meio de dispositivos eletr\u00f4nicos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Casos de golpes e investiga\u00e7\u00e3o<\/h3>\n\n\n\n<p>No primeiro semestre de 2024, apenas no estado de S\u00e3o Paulo, foram registrados mais de 500 boletins de ocorr\u00eancia relacionados a golpes envolvendo o \u201cJogo do Tigrinho\u201d, conforme dados da Secretaria de Seguran\u00e7a P\u00fablica (SSP). A Pol\u00edcia Civil de S\u00e3o Paulo est\u00e1 investigando a participa\u00e7\u00e3o de organiza\u00e7\u00f5es criminosas nesses delitos, que utilizam a plataforma para prometer dinheiro f\u00e1cil e atraem usu\u00e1rios por meio de perfis falsos e grupos nas redes sociais.<\/p>\n\n\n\n<p>O \u201cJogo do Tigrinho\u201d \u00e9 considerado um jogo de azar, o que pode levar ao v\u00edcio, j\u00e1 que os ganhos dependem exclusivamente da sorte do jogador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio da Fazenda publicou, nesta quarta-feira, 31, uma portaria no Di\u00e1rio Oficial que define crit\u00e9rios t\u00e9cnicos para jogos de azar online, como o popular &#8230; <a title=\"Governo estabelece novas regras para jogos de azar online\" class=\"read-more\" href=\"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/\" aria-label=\"Read more about Governo estabelece novas regras para jogos de azar online\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":6881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[13],"tags":[31],"class_list":["post-6880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-brasil","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo estabelece novas regras para jogos de azar online<\/title>\n<meta name=\"description\" content=\"O Minist\u00e9rio da Fazenda publicou, nesta quarta, 31, uma portaria no Di\u00e1rio Oficial que define crit\u00e9rios t\u00e9cnicos para jogos de azar online\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo estabelece novas regras para jogos de azar online\" \/>\n<meta property=\"og:description\" content=\"O Minist\u00e9rio da Fazenda publicou, nesta quarta, 31, uma portaria no Di\u00e1rio Oficial que define crit\u00e9rios t\u00e9cnicos para jogos de azar online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/\" \/>\n<meta property=\"og:site_name\" content=\"LatAm Reports\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/latamreports\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-31T18:21:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-31T18:21:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/latamreports.com\/br\/wp-content\/uploads\/Design-sem-nome-4-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"LatAm Reports Redatores da Equipe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@latamreports\" \/>\n<meta name=\"twitter:site\" content=\"@latamreports\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"LatAm Reports Redatores da Equipe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/governo-estabelece-novas-regras-para-jogos-de-azar-online\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/governo-estabelece-novas-regras-para-jogos-de-azar-online\\\/\"},\"author\":{\"name\":\"LatAm Reports Redatores da Equipe\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/person\\\/a561f2de7e5ccabfab38d239b39fdb70\"},\"headline\":\"Governo estabelece novas regras para jogos de azar online\",\"datePublished\":\"2024-07-31T18:21:28+00:00\",\"dateModified\":\"2024-07-31T18:21:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/governo-estabelece-novas-regras-para-jogos-de-azar-online\\\/\"},\"wordCount\":464,\"publisher\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/governo-estabelece-novas-regras-para-jogos-de-azar-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/Design-sem-nome-4-2.png\",\"keywords\":[\"Brasil\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/governo-estabelece-novas-regras-para-jogos-de-azar-online\\\/\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/governo-estabelece-novas-regras-para-jogos-de-azar-online\\\/\",\"name\":\"Governo estabelece novas regras para jogos de azar online\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/governo-estabelece-novas-regras-para-jogos-de-azar-online\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/governo-estabelece-novas-regras-para-jogos-de-azar-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/Design-sem-nome-4-2.png\",\"datePublished\":\"2024-07-31T18:21:28+00:00\",\"dateModified\":\"2024-07-31T18:21:30+00:00\",\"description\":\"O Minist\u00e9rio da Fazenda publicou, nesta quarta, 31, uma portaria no Di\u00e1rio Oficial que define crit\u00e9rios t\u00e9cnicos para jogos de azar online\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/governo-estabelece-novas-regras-para-jogos-de-azar-online\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamreports.com\\\/br\\\/governo-estabelece-novas-regras-para-jogos-de-azar-online\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/governo-estabelece-novas-regras-para-jogos-de-azar-online\\\/#primaryimage\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/Design-sem-nome-4-2.png\",\"contentUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/Design-sem-nome-4-2.png\",\"width\":1200,\"height\":630,\"caption\":\"novas regras para jogos de azar online\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/governo-estabelece-novas-regras-para-jogos-de-azar-online\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo estabelece novas regras para jogos de azar online\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\",\"name\":\"LatAm Reports\",\"description\":\"Not\u00edcias e opini\u00f5es de todas as Am\u00e9ricas\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamreports.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\",\"name\":\"LatAm Reports\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/cropped-PNG2.png\",\"contentUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/cropped-PNG2.png\",\"width\":2522,\"height\":1014,\"caption\":\"LatAm Reports\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/latamreports\",\"https:\\\/\\\/x.com\\\/latamreports\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/person\\\/a561f2de7e5ccabfab38d239b39fdb70\",\"name\":\"LatAm Reports Redatores da Equipe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dcdcc93cc5edddd2f3ef77245866172c7d7241a11ad58e1959aa824f2fae81f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dcdcc93cc5edddd2f3ef77245866172c7d7241a11ad58e1959aa824f2fae81f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dcdcc93cc5edddd2f3ef77245866172c7d7241a11ad58e1959aa824f2fae81f6?s=96&d=mm&r=g\",\"caption\":\"LatAm Reports Redatores da Equipe\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo estabelece novas regras para jogos de azar online","description":"O Minist\u00e9rio da Fazenda publicou, nesta quarta, 31, uma portaria no Di\u00e1rio Oficial que define crit\u00e9rios t\u00e9cnicos para jogos de azar online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/","og_locale":"en_US","og_type":"article","og_title":"Governo estabelece novas regras para jogos de azar online","og_description":"O Minist\u00e9rio da Fazenda publicou, nesta quarta, 31, uma portaria no Di\u00e1rio Oficial que define crit\u00e9rios t\u00e9cnicos para jogos de azar online","og_url":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/","og_site_name":"LatAm Reports","article_publisher":"https:\/\/facebook.com\/latamreports","article_published_time":"2024-07-31T18:21:28+00:00","article_modified_time":"2024-07-31T18:21:30+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/Design-sem-nome-4-2.png","type":"image\/png"}],"author":"LatAm Reports Redatores da Equipe","twitter_card":"summary_large_image","twitter_creator":"@latamreports","twitter_site":"@latamreports","twitter_misc":{"Written by":"LatAm Reports Redatores da Equipe","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/#article","isPartOf":{"@id":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/"},"author":{"name":"LatAm Reports Redatores da Equipe","@id":"https:\/\/latamreports.com\/br\/#\/schema\/person\/a561f2de7e5ccabfab38d239b39fdb70"},"headline":"Governo estabelece novas regras para jogos de azar online","datePublished":"2024-07-31T18:21:28+00:00","dateModified":"2024-07-31T18:21:30+00:00","mainEntityOfPage":{"@id":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/"},"wordCount":464,"publisher":{"@id":"https:\/\/latamreports.com\/br\/#organization"},"image":{"@id":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/#primaryimage"},"thumbnailUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/Design-sem-nome-4-2.png","keywords":["Brasil"],"articleSection":["Pol\u00edtica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/","url":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/","name":"Governo estabelece novas regras para jogos de azar online","isPartOf":{"@id":"https:\/\/latamreports.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/#primaryimage"},"image":{"@id":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/#primaryimage"},"thumbnailUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/Design-sem-nome-4-2.png","datePublished":"2024-07-31T18:21:28+00:00","dateModified":"2024-07-31T18:21:30+00:00","description":"O Minist\u00e9rio da Fazenda publicou, nesta quarta, 31, uma portaria no Di\u00e1rio Oficial que define crit\u00e9rios t\u00e9cnicos para jogos de azar online","breadcrumb":{"@id":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/#primaryimage","url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/Design-sem-nome-4-2.png","contentUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/Design-sem-nome-4-2.png","width":1200,"height":630,"caption":"novas regras para jogos de azar online"},{"@type":"BreadcrumbList","@id":"https:\/\/latamreports.com\/br\/governo-estabelece-novas-regras-para-jogos-de-azar-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/latamreports.com\/br\/"},{"@type":"ListItem","position":2,"name":"Governo estabelece novas regras para jogos de azar online"}]},{"@type":"WebSite","@id":"https:\/\/latamreports.com\/br\/#website","url":"https:\/\/latamreports.com\/br\/","name":"LatAm Reports","description":"Not\u00edcias e opini\u00f5es de todas as Am\u00e9ricas","publisher":{"@id":"https:\/\/latamreports.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamreports.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/latamreports.com\/br\/#organization","name":"LatAm Reports","url":"https:\/\/latamreports.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/latamreports.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/cropped-PNG2.png","contentUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/cropped-PNG2.png","width":2522,"height":1014,"caption":"LatAm Reports"},"image":{"@id":"https:\/\/latamreports.com\/br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/latamreports","https:\/\/x.com\/latamreports"]},{"@type":"Person","@id":"https:\/\/latamreports.com\/br\/#\/schema\/person\/a561f2de7e5ccabfab38d239b39fdb70","name":"LatAm Reports Redatores da Equipe","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/dcdcc93cc5edddd2f3ef77245866172c7d7241a11ad58e1959aa824f2fae81f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dcdcc93cc5edddd2f3ef77245866172c7d7241a11ad58e1959aa824f2fae81f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dcdcc93cc5edddd2f3ef77245866172c7d7241a11ad58e1959aa824f2fae81f6?s=96&d=mm&r=g","caption":"LatAm Reports Redatores da Equipe"}}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/6880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/comments?post=6880"}],"version-history":[{"count":2,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/6880\/revisions"}],"predecessor-version":[{"id":6883,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/6880\/revisions\/6883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/media\/6881"}],"wp:attachment":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/media?parent=6880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/categories?post=6880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/tags?post=6880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}