{"id":12848,"date":"2025-08-04T21:47:10","date_gmt":"2025-08-04T21:47:10","guid":{"rendered":"https:\/\/latamreports.com\/br\/?p=12848"},"modified":"2025-08-04T21:47:36","modified_gmt":"2025-08-04T21:47:36","slug":"bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos","status":"publish","type":"post","link":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/","title":{"rendered":"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal da bacia de santos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A empresa petroleira brit\u00e2nica BP Energy anunciou sua maior descoberta em 25 anos, nesta segunda-feira, 4: um reservat\u00f3rio de petr\u00f3leo, no pr\u00e9-sal da bacia de Santos, no litoral do Rio de Janeiro. Segundo informa\u00e7\u00f5es divulgadas pela <em><a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2025-08\/petroleira-britanica-bp-anuncia-descoberta-significativa-no-pre-sal#:~:text=A%20petroleira%20brit%C3%A2nica%20BP%20Energy,da%20empresa%20em%2025%20anos.\">Ag\u00eancia Brasil<\/a><\/em>, o po\u00e7o fica no bloco Bumerangue, e est\u00e1 a uma profundidade de 5.855 metros. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O po\u00e7o 1-BP-13-SPS est\u00e1 localizado a 404 quil\u00f4metros da costa do Rio de Janeiro, e a dist\u00e2ncia equivale, por exemplo, ao trajeto entre as cidades do Rio e S\u00e3o Paulo. Segundo a BP Energy, a perfura\u00e7\u00e3o atravessou um reservat\u00f3rio com mais de 300 km\u00b2, com presen\u00e7a de hidrocarbonetos de alta qualidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O vice-presidente de Produ\u00e7\u00e3o e Opera\u00e7\u00f5es da empresa, Gordon Birrell, classificou a descoberta como &#8220;significativa&#8221;. <\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Ele destacou o entusiasmo da BP com o resultado e afirmou que a inten\u00e7\u00e3o \u00e9 consolidar um centro estrat\u00e9gico de opera\u00e7\u00f5es no pa\u00eds.<\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">Embora o resultado inicial seja promissor, a empresa informou que as primeiras an\u00e1lises indicaram n\u00edveis elevados de di\u00f3xido de carbono (CO\u2082). O g\u00e1s, que contribui para o efeito estufa, est\u00e1 presente em grandes propor\u00e7\u00f5es nos reservat\u00f3rios do pr\u00e9-sal. Por isso, novas avalia\u00e7\u00f5es ser\u00e3o conduzidas para entender melhor o potencial da \u00e1rea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jean Paul Prates, ex-presidente da <a href=\"https:\/\/latamreports.com\/br\/brasil-contradiz-discurso-ambiental-ao-investir-em-petroleo-antes-da-cop30\/\">Petrobras<\/a>, comentou a descoberta nas redes sociais. Ele destacou que o teor de CO\u2082 \u00e9 decisivo para a viabilidade econ\u00f4mica do campo. Como exemplo, citou o campo de Libra, com 40% de CO\u2082, onde a produ\u00e7\u00e3o foi viabilizada. J\u00e1 o campo de J\u00fapiter, com 80%, continua parado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo Prates, altos n\u00edveis de CO\u2082 exigem solu\u00e7\u00f5es caras. \u00c9 necess\u00e1rio separar o g\u00e1s, reinjet\u00e1-lo ou encontrar uso comercial, o que depende de tecnologia avan\u00e7ada e de mercado. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cVamos torcer para que o Bumerangue esteja mais perto de Libra do que de J\u00fapiter\u201d, escreveu. Para ele, \u00e9 cedo para comemorar.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar do alerta, Prates ressaltou que a descoberta refor\u00e7a a relev\u00e2ncia global do pr\u00e9-sal. No entanto, ele apontou que o Brasil precisa garantir estabilidade regulat\u00f3ria, vis\u00e3o estrat\u00e9gica e pol\u00edtica p\u00fablica para transformar o potencial em produ\u00e7\u00e3o real.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Os reservat\u00f3rios do pr\u00e9-sal se encontram entre 5 mil e 7 mil metros de profundidade. <\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">Hoje, essa faixa \u00e9 respons\u00e1vel por quase 80% da produ\u00e7\u00e3o nacional de petr\u00f3leo, segundo a Ag\u00eancia Nacional do Petr\u00f3leo, G\u00e1s Natural e Biocombust\u00edveis (ANP).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A BP det\u00e9m 100% do bloco Bumerangue, arrematado em leil\u00e3o realizado em dezembro de 2022. Pelo contrato assinado com o governo federal, a empresa ter\u00e1 que entregar \u00e0 Uni\u00e3o 5,9% do \u00f3leo excedente, ap\u00f3s o abatimento dos custos de produ\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m do Bumerangue, a BP tem participa\u00e7\u00e3o em mais oito blocos mar\u00edtimos no Brasil, sendo operadora de quatro deles. O pr\u00f3ximo projeto de perfura\u00e7\u00e3o est\u00e1 previsto para 2026, no bloco Tupinamb\u00e1, tamb\u00e9m no pr\u00e9-sal da Bacia de Santos. O ativo foi adquirido com um lance de R$ 7 milh\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Presente no Brasil desde 1957, a BP atua em diversas \u00e1reas do setor energ\u00e9tico. Explora petr\u00f3leo e g\u00e1s, fornece combust\u00edvel para avia\u00e7\u00e3o e transporte mar\u00edtimo, opera com biocombust\u00edveis e tamb\u00e9m investe em energia solar. A marca Castrol, de lubrificantes, tamb\u00e9m faz parte do portf\u00f3lio da companhia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A empresa participa ainda da GNA II, maior usina termel\u00e9trica a g\u00e1s natural da Am\u00e9rica Latina. A estrutura, localizada no Porto do A\u00e7u (RJ), foi inaugurada nesta semana com a presen\u00e7a do presidente Luiz In\u00e1cio Lula da Silva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A marca BP, que originalmente significava <em>British Petroleum<\/em>, passou a adotar o conceito <em>Beyond Petroleum<\/em> nos anos 2000. A mudan\u00e7a buscou refletir a diversifica\u00e7\u00e3o dos neg\u00f3cios da empresa para al\u00e9m do petr\u00f3leo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar do novo momento, a BP ainda carrega marcas do passado. Em 2010, protagonizou um dos maiores desastres ambientais da hist\u00f3ria, com o vazamento de petr\u00f3leo no Golfo do M\u00e9xico. O acidente durou quase tr\u00eas meses. Como consequ\u00eancia, a companhia teve que arcar com bilh\u00f5es de d\u00f3lares em indeniza\u00e7\u00f5es.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1653122&amp;o=node\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1653122&amp;o=node\" alt=\"\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A empresa petroleira brit\u00e2nica BP Energy anunciou sua maior descoberta em 25 anos, nesta segunda-feira, 4: um reservat\u00f3rio de petr\u00f3leo, no pr\u00e9-sal da bacia de &#8230; <a title=\"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal da bacia de santos\" class=\"read-more\" href=\"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/\" aria-label=\"Read more about BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal da bacia de santos\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":12849,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[13],"tags":[31],"class_list":["post-12848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-brasil","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal<\/title>\n<meta name=\"description\" content=\"A empresa petroleira brit\u00e2nica BP Energy anunciou sua maior descoberta em 25 anos, nesta segunda-feira, 4: um reservat\u00f3rio de petr\u00f3leo...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal\" \/>\n<meta property=\"og:description\" content=\"A empresa petroleira brit\u00e2nica BP Energy anunciou sua maior descoberta em 25 anos, nesta segunda-feira, 4: um reservat\u00f3rio de petr\u00f3leo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/\" \/>\n<meta property=\"og:site_name\" content=\"LatAm Reports\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/latamreports\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-04T21:47:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-04T21:47:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/latamreports.com\/br\/wp-content\/uploads\/bp-anuncia-novo-poco-de-petroleo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"LatAm Reports Redatores da Equipe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@latamreports\" \/>\n<meta name=\"twitter:site\" content=\"@latamreports\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"LatAm Reports Redatores da Equipe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\\\/\"},\"author\":{\"name\":\"LatAm Reports Redatores da Equipe\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/person\\\/a561f2de7e5ccabfab38d239b39fdb70\"},\"headline\":\"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal da bacia de santos\",\"datePublished\":\"2025-08-04T21:47:10+00:00\",\"dateModified\":\"2025-08-04T21:47:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\\\/\"},\"wordCount\":714,\"publisher\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/bp-anuncia-novo-poco-de-petroleo.png\",\"keywords\":[\"Brasil\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\\\/\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\\\/\",\"name\":\"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/bp-anuncia-novo-poco-de-petroleo.png\",\"datePublished\":\"2025-08-04T21:47:10+00:00\",\"dateModified\":\"2025-08-04T21:47:36+00:00\",\"description\":\"A empresa petroleira brit\u00e2nica BP Energy anunciou sua maior descoberta em 25 anos, nesta segunda-feira, 4: um reservat\u00f3rio de petr\u00f3leo...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamreports.com\\\/br\\\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/bp-anuncia-novo-poco-de-petroleo.png\",\"contentUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/bp-anuncia-novo-poco-de-petroleo.png\",\"width\":1200,\"height\":630,\"caption\":\"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal da bacia de santos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal da bacia de santos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\",\"name\":\"LatAm Reports\",\"description\":\"Not\u00edcias e opini\u00f5es de todas as Am\u00e9ricas\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamreports.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\",\"name\":\"LatAm Reports\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/cropped-PNG2.png\",\"contentUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/cropped-PNG2.png\",\"width\":2522,\"height\":1014,\"caption\":\"LatAm Reports\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/latamreports\",\"https:\\\/\\\/x.com\\\/latamreports\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/person\\\/a561f2de7e5ccabfab38d239b39fdb70\",\"name\":\"LatAm Reports Redatores da Equipe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g\",\"caption\":\"LatAm Reports Redatores da Equipe\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal","description":"A empresa petroleira brit\u00e2nica BP Energy anunciou sua maior descoberta em 25 anos, nesta segunda-feira, 4: um reservat\u00f3rio de petr\u00f3leo...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/","og_locale":"en_US","og_type":"article","og_title":"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal","og_description":"A empresa petroleira brit\u00e2nica BP Energy anunciou sua maior descoberta em 25 anos, nesta segunda-feira, 4: um reservat\u00f3rio de petr\u00f3leo...","og_url":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/","og_site_name":"LatAm Reports","article_publisher":"https:\/\/facebook.com\/latamreports","article_published_time":"2025-08-04T21:47:10+00:00","article_modified_time":"2025-08-04T21:47:36+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/bp-anuncia-novo-poco-de-petroleo.png","type":"image\/png"}],"author":"LatAm Reports Redatores da Equipe","twitter_card":"summary_large_image","twitter_creator":"@latamreports","twitter_site":"@latamreports","twitter_misc":{"Written by":"LatAm Reports Redatores da Equipe","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/#article","isPartOf":{"@id":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/"},"author":{"name":"LatAm Reports Redatores da Equipe","@id":"https:\/\/latamreports.com\/br\/#\/schema\/person\/a561f2de7e5ccabfab38d239b39fdb70"},"headline":"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal da bacia de santos","datePublished":"2025-08-04T21:47:10+00:00","dateModified":"2025-08-04T21:47:36+00:00","mainEntityOfPage":{"@id":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/"},"wordCount":714,"publisher":{"@id":"https:\/\/latamreports.com\/br\/#organization"},"image":{"@id":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/bp-anuncia-novo-poco-de-petroleo.png","keywords":["Brasil"],"articleSection":["Pol\u00edtica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/","url":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/","name":"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal","isPartOf":{"@id":"https:\/\/latamreports.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/#primaryimage"},"image":{"@id":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/bp-anuncia-novo-poco-de-petroleo.png","datePublished":"2025-08-04T21:47:10+00:00","dateModified":"2025-08-04T21:47:36+00:00","description":"A empresa petroleira brit\u00e2nica BP Energy anunciou sua maior descoberta em 25 anos, nesta segunda-feira, 4: um reservat\u00f3rio de petr\u00f3leo...","breadcrumb":{"@id":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/#primaryimage","url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/bp-anuncia-novo-poco-de-petroleo.png","contentUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/bp-anuncia-novo-poco-de-petroleo.png","width":1200,"height":630,"caption":"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal da bacia de santos"},{"@type":"BreadcrumbList","@id":"https:\/\/latamreports.com\/br\/bp-energy-anuncia-descoberta-de-petroleo-no-pre-sal-da-bacia-de-santos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/latamreports.com\/br\/"},{"@type":"ListItem","position":2,"name":"BP Energy anuncia descoberta de petr\u00f3leo no pr\u00e9-sal da bacia de santos"}]},{"@type":"WebSite","@id":"https:\/\/latamreports.com\/br\/#website","url":"https:\/\/latamreports.com\/br\/","name":"LatAm Reports","description":"Not\u00edcias e opini\u00f5es de todas as Am\u00e9ricas","publisher":{"@id":"https:\/\/latamreports.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamreports.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/latamreports.com\/br\/#organization","name":"LatAm Reports","url":"https:\/\/latamreports.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/latamreports.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/cropped-PNG2.png","contentUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/cropped-PNG2.png","width":2522,"height":1014,"caption":"LatAm Reports"},"image":{"@id":"https:\/\/latamreports.com\/br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/latamreports","https:\/\/x.com\/latamreports"]},{"@type":"Person","@id":"https:\/\/latamreports.com\/br\/#\/schema\/person\/a561f2de7e5ccabfab38d239b39fdb70","name":"LatAm Reports Redatores da Equipe","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g","caption":"LatAm Reports Redatores da Equipe"}}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/12848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/comments?post=12848"}],"version-history":[{"count":2,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/12848\/revisions"}],"predecessor-version":[{"id":12851,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/12848\/revisions\/12851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/media\/12849"}],"wp:attachment":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/media?parent=12848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/categories?post=12848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/tags?post=12848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}