{"id":11945,"date":"2025-05-09T11:51:42","date_gmt":"2025-05-09T11:51:42","guid":{"rendered":"https:\/\/latamreports.com\/br\/?p=11945"},"modified":"2025-05-09T11:51:45","modified_gmt":"2025-05-09T11:51:45","slug":"leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo","status":"publish","type":"post","link":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/","title":{"rendered":"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja seja &#8216;farol nas noites do mundo&#8217;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Em sua primeira homilia como pont\u00edfice, o <a href=\"https:\/\/latamreports.com\/es\/pueblo-peruano-celebra-con-orgullo-la-eleccion-del-papa-leon-xiv-es-uno-de-los-nuestros\/\">papa <\/a>Le\u00e3o XIV defendeu uma Igreja Cat\u00f3lica mais pr\u00f3xima dos fi\u00e9is e guiada pela santidade. Na missa celebrada nesta sexta-feira, 9, com cardeais na Capela Sistina, ele pediu que a Igreja seja \u201cum farol que ilumina as noites do mundo\u201d e alertou para o decl\u00ednio da f\u00e9 diante do culto ao dinheiro, prazer e poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le\u00e3o XIV ressaltou que deseja conduzir a Igreja como uma \u201carca de salva\u00e7\u00e3o\u201d em tempos dif\u00edceis, rejeitando a ideia de uma f\u00e9 sustentada por apar\u00eancia ou estrutura, e sim por a\u00e7\u00e3o e compromisso. \u201cN\u00e3o \u00e9 a grandiosidade de seus edif\u00edcios que identifica a Igreja, mas sim a santidade de seus membros\u201d, afirmou. A fala ecoa o estilo pastoral do papa Francisco, seu antecessor, e indica a continuidade de uma vis\u00e3o mais humanizada e mission\u00e1ria da institui\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante a homilia, o novo <a href=\"https:\/\/latamreports.com\/es\/quien-sera-el-proximo-papa-los-nombres-que-suenan-tras-la-muerte-de-francisco\/\">papa <\/a>fez cr\u00edticas ao que chamou de &#8220;ate\u00edsmo pr\u00e1tico&#8221;. Para ele, muitos crist\u00e3os acabam reduzindo Jesus \u00e0 imagem de um l\u00edder carism\u00e1tico, ignorando sua verdadeira natureza divina. Le\u00e3o XIV lamentou que, em muitos contextos, a f\u00e9 crist\u00e3 seja vista como coisa de gente fraca, superada por cren\u00e7as no dinheiro, na tecnologia e no sucesso material.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em sua fala, o papa tamb\u00e9m prestou homenagem ao ap\u00f3stolo Pedro, primeiro l\u00edder da Igreja e s\u00edmbolo do papado. Pediu sua b\u00ean\u00e7\u00e3o para os desafios que enfrentar\u00e1 \u00e0 frente da Santa S\u00e9. <\/p>\n\n\n\n<h6 class=\"wp-block-heading\">No pr\u00f3ximo doming, 11, Le\u00e3o XIV deve recitar a ora\u00e7\u00e3o do Regina Coeli da sacada central da Bas\u00edlica de S\u00e3o Pedro, momento tradicional que marcar\u00e1 seu primeiro encontro com os fi\u00e9is em pra\u00e7a p\u00fablica.<\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">Eleito nesta quinta-feira, 8, Le\u00e3o XIV \u00e9 o primeiro papa nascido nos Estados Unidos e tamb\u00e9m possui cidadania peruana. Robert Francis Prevost tem 69 anos, pertence \u00e0 ordem agostiniana e ganhou destaque pela atua\u00e7\u00e3o pastoral no Peru, onde foi nomeado bispo de Chiclayo em 2015. Durante seu discurso inaugural, fez quest\u00e3o de falar em espanhol para homenagear a comunidade que o acolheu na Am\u00e9rica Latina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em sua primeira homilia como pont\u00edfice, o papa Le\u00e3o XIV defendeu uma Igreja Cat\u00f3lica mais pr\u00f3xima dos fi\u00e9is e guiada pela santidade. Na missa celebrada &#8230; <a title=\"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja seja &#8216;farol nas noites do mundo&#8217;\" class=\"read-more\" href=\"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/\" aria-label=\"Read more about Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja seja &#8216;farol nas noites do mundo&#8217;\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":11946,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[13],"tags":[],"class_list":["post-11945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja...<\/title>\n<meta name=\"description\" content=\"Em sua primeira homilia como pont\u00edfice, o papa Le\u00e3o XIV defendeu uma Igreja Cat\u00f3lica mais pr\u00f3xima dos fi\u00e9is e guiada pela santidade.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja...\" \/>\n<meta property=\"og:description\" content=\"Em sua primeira homilia como pont\u00edfice, o papa Le\u00e3o XIV defendeu uma Igreja Cat\u00f3lica mais pr\u00f3xima dos fi\u00e9is e guiada pela santidade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"LatAm Reports\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/latamreports\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-09T11:51:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T11:51:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-2025-05-09T074552.746.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"LatAm Reports Redatores da Equipe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@latamreports\" \/>\n<meta name=\"twitter:site\" content=\"@latamreports\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"LatAm Reports Redatores da Equipe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\\\/\"},\"author\":{\"name\":\"LatAm Reports Redatores da Equipe\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/person\\\/a561f2de7e5ccabfab38d239b39fdb70\"},\"headline\":\"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja seja &#8216;farol nas noites do mundo&#8217;\",\"datePublished\":\"2025-05-09T11:51:42+00:00\",\"dateModified\":\"2025-05-09T11:51:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\\\/\"},\"wordCount\":379,\"publisher\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/design-2025-05-09T074552.746.png\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\\\/\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\\\/\",\"name\":\"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja...\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/design-2025-05-09T074552.746.png\",\"datePublished\":\"2025-05-09T11:51:42+00:00\",\"dateModified\":\"2025-05-09T11:51:45+00:00\",\"description\":\"Em sua primeira homilia como pont\u00edfice, o papa Le\u00e3o XIV defendeu uma Igreja Cat\u00f3lica mais pr\u00f3xima dos fi\u00e9is e guiada pela santidade.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamreports.com\\\/br\\\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/design-2025-05-09T074552.746.png\",\"contentUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/design-2025-05-09T074552.746.png\",\"width\":1200,\"height\":630,\"caption\":\"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja seja 'farol nas noites do mundo'\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja seja &#8216;farol nas noites do mundo&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\",\"name\":\"LatAm Reports\",\"description\":\"Not\u00edcias e opini\u00f5es de todas as Am\u00e9ricas\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamreports.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\",\"name\":\"LatAm Reports\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/cropped-PNG2.png\",\"contentUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/cropped-PNG2.png\",\"width\":2522,\"height\":1014,\"caption\":\"LatAm Reports\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/latamreports\",\"https:\\\/\\\/x.com\\\/latamreports\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/person\\\/a561f2de7e5ccabfab38d239b39fdb70\",\"name\":\"LatAm Reports Redatores da Equipe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g\",\"caption\":\"LatAm Reports Redatores da Equipe\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja...","description":"Em sua primeira homilia como pont\u00edfice, o papa Le\u00e3o XIV defendeu uma Igreja Cat\u00f3lica mais pr\u00f3xima dos fi\u00e9is e guiada pela santidade.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/","og_locale":"en_US","og_type":"article","og_title":"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja...","og_description":"Em sua primeira homilia como pont\u00edfice, o papa Le\u00e3o XIV defendeu uma Igreja Cat\u00f3lica mais pr\u00f3xima dos fi\u00e9is e guiada pela santidade.","og_url":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/","og_site_name":"LatAm Reports","article_publisher":"https:\/\/facebook.com\/latamreports","article_published_time":"2025-05-09T11:51:42+00:00","article_modified_time":"2025-05-09T11:51:45+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-2025-05-09T074552.746.png","type":"image\/png"}],"author":"LatAm Reports Redatores da Equipe","twitter_card":"summary_large_image","twitter_creator":"@latamreports","twitter_site":"@latamreports","twitter_misc":{"Written by":"LatAm Reports Redatores da Equipe","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/#article","isPartOf":{"@id":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/"},"author":{"name":"LatAm Reports Redatores da Equipe","@id":"https:\/\/latamreports.com\/br\/#\/schema\/person\/a561f2de7e5ccabfab38d239b39fdb70"},"headline":"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja seja &#8216;farol nas noites do mundo&#8217;","datePublished":"2025-05-09T11:51:42+00:00","dateModified":"2025-05-09T11:51:45+00:00","mainEntityOfPage":{"@id":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/"},"wordCount":379,"publisher":{"@id":"https:\/\/latamreports.com\/br\/#organization"},"image":{"@id":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-2025-05-09T074552.746.png","articleSection":["Pol\u00edtica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/","url":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/","name":"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja...","isPartOf":{"@id":"https:\/\/latamreports.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/#primaryimage"},"image":{"@id":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-2025-05-09T074552.746.png","datePublished":"2025-05-09T11:51:42+00:00","dateModified":"2025-05-09T11:51:45+00:00","description":"Em sua primeira homilia como pont\u00edfice, o papa Le\u00e3o XIV defendeu uma Igreja Cat\u00f3lica mais pr\u00f3xima dos fi\u00e9is e guiada pela santidade.","breadcrumb":{"@id":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/#primaryimage","url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-2025-05-09T074552.746.png","contentUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-2025-05-09T074552.746.png","width":1200,"height":630,"caption":"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja seja 'farol nas noites do mundo'"},{"@type":"BreadcrumbList","@id":"https:\/\/latamreports.com\/br\/leao-xiv-celebra-1a-missa-como-papa-e-pede-que-igreja-seja-farol-nas-noites-do-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/latamreports.com\/br\/"},{"@type":"ListItem","position":2,"name":"Le\u00e3o XIV celebra 1\u00aa missa como papa e pede que Igreja seja &#8216;farol nas noites do mundo&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/latamreports.com\/br\/#website","url":"https:\/\/latamreports.com\/br\/","name":"LatAm Reports","description":"Not\u00edcias e opini\u00f5es de todas as Am\u00e9ricas","publisher":{"@id":"https:\/\/latamreports.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamreports.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/latamreports.com\/br\/#organization","name":"LatAm Reports","url":"https:\/\/latamreports.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/latamreports.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/cropped-PNG2.png","contentUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/cropped-PNG2.png","width":2522,"height":1014,"caption":"LatAm Reports"},"image":{"@id":"https:\/\/latamreports.com\/br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/latamreports","https:\/\/x.com\/latamreports"]},{"@type":"Person","@id":"https:\/\/latamreports.com\/br\/#\/schema\/person\/a561f2de7e5ccabfab38d239b39fdb70","name":"LatAm Reports Redatores da Equipe","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g","caption":"LatAm Reports Redatores da Equipe"}}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/11945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/comments?post=11945"}],"version-history":[{"count":1,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/11945\/revisions"}],"predecessor-version":[{"id":11947,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/11945\/revisions\/11947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/media\/11946"}],"wp:attachment":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/media?parent=11945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/categories?post=11945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/tags?post=11945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}