{"id":11536,"date":"2025-04-03T21:24:36","date_gmt":"2025-04-03T21:24:36","guid":{"rendered":"https:\/\/latamreports.com\/br\/?p=11536"},"modified":"2025-04-03T21:24:38","modified_gmt":"2025-04-03T21:24:38","slug":"popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes","status":"publish","type":"post","link":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/","title":{"rendered":"Popularidade em queda: economia vira desafio central para Lula a um ano e meio das elei\u00e7\u00f5es"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A popularidade do presidente <a href=\"https:\/\/latamreports.com\/br\/reprovacao-ao-governo-lula-atinge-56-maior-indice-desde-o-inicio-do-mandato-aponta-quaest\/\">Lula<\/a> (PT) vem desmoronando em ritmo acelerado. Segundo a nova pesquisa Genial\/Quaest, a desaprova\u00e7\u00e3o do governo subiu para 56%, o maior \u00edndice desde o in\u00edcio do mandato. O cen\u00e1rio, marcado por infla\u00e7\u00e3o alta, queda no poder de compra e desgaste pol\u00edtico, coloca o governo sob press\u00e3o num momento decisivo: faltam pouco mais de 18 meses para as elei\u00e7\u00f5es de 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A avalia\u00e7\u00e3o negativa ganhou for\u00e7a entre o fim de 2024 e o primeiro trimestre deste ano. Uma sequ\u00eancia de fatores contribuiu para esse cen\u00e1rio, como a alta nos alimentos, o avan\u00e7o do d\u00f3lar, juros persistentemente elevados e a frustra\u00e7\u00e3o com promessas n\u00e3o cumpridas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mesmo ap\u00f3s trocar o comando da Secretaria de Comunica\u00e7\u00e3o, com a chegada do marqueteiro Sid\u00f4nio Palmeira, o Planalto n\u00e3o conseguiu estancar a queda. Sid\u00f4nio tentou reposicionar a imagem de Lula, apostando na compara\u00e7\u00e3o com o governo Bolsonaro e divulgando dados positivos do PIB, gera\u00e7\u00e3o de empregos e aumento do sal\u00e1rio m\u00ednimo. Mas at\u00e9 agora, os resultados n\u00e3o apareceram.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Enquanto isso, a infla\u00e7\u00e3o ultrapassou o teto da meta e fechou 2024 em 4,83%. O impacto foi sentido principalmente nos alimentos. O caf\u00e9 subiu quase 40% no ano. A carne teve alta de mais de 20%. E o subgrupo \u201calimenta\u00e7\u00e3o no domic\u00edlio\u201d registrou aumento superior a 8%.<\/h6>\n\n\n\n<p class=\"wp-block-paragraph\"> A situa\u00e7\u00e3o \u00e9 ainda mais cr\u00edtica no Nordeste, onde Lula concentra parte expressiva de sua base eleitoral. Em estados como Bahia e Sergipe, os pre\u00e7os dispararam.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a press\u00e3o popular crescendo, o governo zerou o imposto de importa\u00e7\u00e3o sobre produtos como carne, milho e caf\u00e9. A medida entrou em vigor em mar\u00e7o, mas analistas apontam que o impacto sobre os pre\u00e7os internos ser\u00e1 limitado. Isso porque o problema n\u00e3o \u00e9 s\u00f3 tribut\u00e1rio, mas envolve tamb\u00e9m fatores internacionais, como quebras de safra e alta dos pre\u00e7os globais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, o d\u00f3lar saltou 27% em 2024. A moeda norte-americana passou de R$ 5,67 para R$ 6,17 em menos de dois meses. A valoriza\u00e7\u00e3o da moeda est\u00e1 ligada \u00e0 inseguran\u00e7a do mercado com o pacote de ajuste fiscal do governo e \u00e0 proposta de ampliar a faixa de isen\u00e7\u00e3o do Imposto de Renda, o que pode reduzir a arrecada\u00e7\u00e3o.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Para o mercado, a condu\u00e7\u00e3o das contas p\u00fablicas \u00e9 um dos pontos mais preocupantes. A d\u00edvida bruta j\u00e1 ultrapassa os 75% do PIB. E sem um corte efetivo de gastos, cresce o temor de que o pa\u00eds se torne mais arriscado para investidores \u2014 o que pressiona ainda mais o c\u00e2mbio, os juros e a infla\u00e7\u00e3o.<\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a mesma pesquisa Quaest, 88% dos agentes do mercado financeiro reprovam a gest\u00e3o de Lula. O ministro da Fazenda, Fernando Haddad, tamb\u00e9m amarga reprova\u00e7\u00e3o alta: 58%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Especialistas apontam que, mesmo sem voto direto, o mercado influencia o clima geral da economia. Se os investidores perdem confian\u00e7a, o impacto chega r\u00e1pido no bolso da popula\u00e7\u00e3o. Juros sobem, cr\u00e9dito encarece e os pre\u00e7os continuam em alta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Internamente, a press\u00e3o por respostas cresceu. O governo lan\u00e7ou uma linha de cr\u00e9dito consignado com FGTS como garantia, voltada a trabalhadores do setor privado. A promessa \u00e9 reduzir os juros pela metade. Tamb\u00e9m foi aprovada a isen\u00e7\u00e3o de IR para quem ganha at\u00e9 R$ 5 mil, com descontos para quem recebe at\u00e9 R$ 7 mil. S\u00e3o medidas populares, mas que enfrentam desafios fiscais e alcance limitado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o economista Andr\u00e9 Galhardo, a proposta do IR vem em boa hora, ainda que atrasada. J\u00e1 o cr\u00e9dito consignado pode beneficiar parte da popula\u00e7\u00e3o endividada. Mas ele alerta: isso n\u00e3o resolve o problema estrutural. \u201cQuem n\u00e3o tem FGTS ou n\u00e3o declara IR continua fora da conta. E o risco \u00e9 gerar mais press\u00e3o sobre os juros no futuro\u201d, diz.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Na avalia\u00e7\u00e3o do cientista pol\u00edtico Carlos Melo, o governo precisa encontrar maneiras de atingir os brasileiros mais pobres e informais. \u201cEsse p\u00fablico ainda n\u00e3o sente melhora real. E sem isso, a <a href=\"https:\/\/latamreports.com\/br\/credito-consignado-com-fgts-vira-alvo-de-criticas-e-disputa-nas-redes-governo-prepara-campanha-de-orientacao\/\">impopularidade<\/a> tende a crescer.\u201d<\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">Na compara\u00e7\u00e3o com os mandatos anteriores, o contraste \u00e9 n\u00edtido. Em 2010, Lula deixou o Planalto com 87% de aprova\u00e7\u00e3o. Hoje, v\u00ea sua imagem abalada por crises econ\u00f4micas, esc\u00e2ndalos passados e um capital pol\u00edtico enfraquecido. Segundo analistas, parte disso \u00e9 heran\u00e7a da gest\u00e3o Dilma Rousseff, do impeachment, da Lava Jato e do mensal\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lula ainda n\u00e3o confirmou se ser\u00e1 candidato em 2026. Mas segue sendo o nome mais forte da esquerda. O problema \u00e9 que, para chegar competitivo, precisa entregar resultados. E o tempo est\u00e1 correndo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As despesas obrigat\u00f3rias seguem subindo. O governo enfrenta press\u00f5es com precat\u00f3rios, BPC e folha de pagamento. A Selic deve encerrar o ano em 15%, o que dificulta o crescimento econ\u00f4mico. E sem receita forte, o espa\u00e7o para novas promessas se estreita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A poucos meses do ciclo eleitoral, o Planalto se v\u00ea diante de um dilema: tentar agradar o eleitor com al\u00edvio no bolso ou manter o compromisso com o equil\u00edbrio fiscal. Ambas as op\u00e7\u00f5es t\u00eam custo pol\u00edtico. E qualquer erro pode custar caro nas urnas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acompanhe o LatAm Reports para mais an\u00e1lises exclusivas sobre pol\u00edtica, economia e os bastidores do poder em Bras\u00edlia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A popularidade do presidente Lula (PT) vem desmoronando em ritmo acelerado. Segundo a nova pesquisa Genial\/Quaest, a desaprova\u00e7\u00e3o do governo subiu para 56%, o maior &#8230; <a title=\"Popularidade em queda: economia vira desafio central para Lula a um ano e meio das elei\u00e7\u00f5es\" class=\"read-more\" href=\"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/\" aria-label=\"Read more about Popularidade em queda: economia vira desafio central para Lula a um ano e meio das elei\u00e7\u00f5es\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":11537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[13],"tags":[31],"class_list":["post-11536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-brasil","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Popularidade em queda: economia vira desafio central para Lula<\/title>\n<meta name=\"description\" content=\"A popularidade do presidente Lula (PT) vem desmoronando em ritmo acelerado. Segundo a nova pesquisa Genial\/Quaest, a desaprova\u00e7\u00e3o do...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Popularidade em queda: economia vira desafio central para Lula\" \/>\n<meta property=\"og:description\" content=\"A popularidade do presidente Lula (PT) vem desmoronando em ritmo acelerado. Segundo a nova pesquisa Genial\/Quaest, a desaprova\u00e7\u00e3o do...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/\" \/>\n<meta property=\"og:site_name\" content=\"LatAm Reports\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/latamreports\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-03T21:24:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-03T21:24:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-2025-04-03T160224.871.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"LatAm Reports Redatores da Equipe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@latamreports\" \/>\n<meta name=\"twitter:site\" content=\"@latamreports\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"LatAm Reports Redatores da Equipe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\\\/\"},\"author\":{\"name\":\"LatAm Reports Redatores da Equipe\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/person\\\/a561f2de7e5ccabfab38d239b39fdb70\"},\"headline\":\"Popularidade em queda: economia vira desafio central para Lula a um ano e meio das elei\u00e7\u00f5es\",\"datePublished\":\"2025-04-03T21:24:36+00:00\",\"dateModified\":\"2025-04-03T21:24:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\\\/\"},\"wordCount\":912,\"publisher\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/design-2025-04-03T160224.871.png\",\"keywords\":[\"Brasil\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\\\/\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\\\/\",\"name\":\"Popularidade em queda: economia vira desafio central para Lula\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/design-2025-04-03T160224.871.png\",\"datePublished\":\"2025-04-03T21:24:36+00:00\",\"dateModified\":\"2025-04-03T21:24:38+00:00\",\"description\":\"A popularidade do presidente Lula (PT) vem desmoronando em ritmo acelerado. Segundo a nova pesquisa Genial\\\/Quaest, a desaprova\u00e7\u00e3o do...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamreports.com\\\/br\\\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/design-2025-04-03T160224.871.png\",\"contentUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/design-2025-04-03T160224.871.png\",\"width\":1200,\"height\":630,\"caption\":\"Popularidade em queda: economia vira desafio central para Lula a um ano e meio das elei\u00e7\u00f5es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Popularidade em queda: economia vira desafio central para Lula a um ano e meio das elei\u00e7\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\",\"name\":\"LatAm Reports\",\"description\":\"Not\u00edcias e opini\u00f5es de todas as Am\u00e9ricas\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamreports.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\",\"name\":\"LatAm Reports\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/cropped-PNG2.png\",\"contentUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/cropped-PNG2.png\",\"width\":2522,\"height\":1014,\"caption\":\"LatAm Reports\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/latamreports\",\"https:\\\/\\\/x.com\\\/latamreports\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/person\\\/a561f2de7e5ccabfab38d239b39fdb70\",\"name\":\"LatAm Reports Redatores da Equipe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g\",\"caption\":\"LatAm Reports Redatores da Equipe\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Popularidade em queda: economia vira desafio central para Lula","description":"A popularidade do presidente Lula (PT) vem desmoronando em ritmo acelerado. Segundo a nova pesquisa Genial\/Quaest, a desaprova\u00e7\u00e3o do...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/","og_locale":"en_US","og_type":"article","og_title":"Popularidade em queda: economia vira desafio central para Lula","og_description":"A popularidade do presidente Lula (PT) vem desmoronando em ritmo acelerado. Segundo a nova pesquisa Genial\/Quaest, a desaprova\u00e7\u00e3o do...","og_url":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/","og_site_name":"LatAm Reports","article_publisher":"https:\/\/facebook.com\/latamreports","article_published_time":"2025-04-03T21:24:36+00:00","article_modified_time":"2025-04-03T21:24:38+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-2025-04-03T160224.871.png","type":"image\/png"}],"author":"LatAm Reports Redatores da Equipe","twitter_card":"summary_large_image","twitter_creator":"@latamreports","twitter_site":"@latamreports","twitter_misc":{"Written by":"LatAm Reports Redatores da Equipe","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/#article","isPartOf":{"@id":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/"},"author":{"name":"LatAm Reports Redatores da Equipe","@id":"https:\/\/latamreports.com\/br\/#\/schema\/person\/a561f2de7e5ccabfab38d239b39fdb70"},"headline":"Popularidade em queda: economia vira desafio central para Lula a um ano e meio das elei\u00e7\u00f5es","datePublished":"2025-04-03T21:24:36+00:00","dateModified":"2025-04-03T21:24:38+00:00","mainEntityOfPage":{"@id":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/"},"wordCount":912,"publisher":{"@id":"https:\/\/latamreports.com\/br\/#organization"},"image":{"@id":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/#primaryimage"},"thumbnailUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-2025-04-03T160224.871.png","keywords":["Brasil"],"articleSection":["Pol\u00edtica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/","url":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/","name":"Popularidade em queda: economia vira desafio central para Lula","isPartOf":{"@id":"https:\/\/latamreports.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/#primaryimage"},"image":{"@id":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/#primaryimage"},"thumbnailUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-2025-04-03T160224.871.png","datePublished":"2025-04-03T21:24:36+00:00","dateModified":"2025-04-03T21:24:38+00:00","description":"A popularidade do presidente Lula (PT) vem desmoronando em ritmo acelerado. Segundo a nova pesquisa Genial\/Quaest, a desaprova\u00e7\u00e3o do...","breadcrumb":{"@id":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/#primaryimage","url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-2025-04-03T160224.871.png","contentUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-2025-04-03T160224.871.png","width":1200,"height":630,"caption":"Popularidade em queda: economia vira desafio central para Lula a um ano e meio das elei\u00e7\u00f5es"},{"@type":"BreadcrumbList","@id":"https:\/\/latamreports.com\/br\/popularidade-em-queda-economia-vira-desafio-central-para-lula-a-um-ano-e-meio-das-eleicoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/latamreports.com\/br\/"},{"@type":"ListItem","position":2,"name":"Popularidade em queda: economia vira desafio central para Lula a um ano e meio das elei\u00e7\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/latamreports.com\/br\/#website","url":"https:\/\/latamreports.com\/br\/","name":"LatAm Reports","description":"Not\u00edcias e opini\u00f5es de todas as Am\u00e9ricas","publisher":{"@id":"https:\/\/latamreports.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamreports.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/latamreports.com\/br\/#organization","name":"LatAm Reports","url":"https:\/\/latamreports.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/latamreports.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/cropped-PNG2.png","contentUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/cropped-PNG2.png","width":2522,"height":1014,"caption":"LatAm Reports"},"image":{"@id":"https:\/\/latamreports.com\/br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/latamreports","https:\/\/x.com\/latamreports"]},{"@type":"Person","@id":"https:\/\/latamreports.com\/br\/#\/schema\/person\/a561f2de7e5ccabfab38d239b39fdb70","name":"LatAm Reports Redatores da Equipe","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g","caption":"LatAm Reports Redatores da Equipe"}}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/11536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/comments?post=11536"}],"version-history":[{"count":1,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/11536\/revisions"}],"predecessor-version":[{"id":11538,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/11536\/revisions\/11538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/media\/11537"}],"wp:attachment":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/media?parent=11536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/categories?post=11536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/tags?post=11536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}