{"id":11163,"date":"2025-03-14T17:43:56","date_gmt":"2025-03-14T17:43:56","guid":{"rendered":"https:\/\/latamreports.com\/br\/?p=11163"},"modified":"2025-03-14T17:43:58","modified_gmt":"2025-03-14T17:43:58","slug":"stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe","status":"publish","type":"post","link":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/","title":{"rendered":"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro e aliados por tentativa de golpe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Primeira Turma do Supremo Tribunal Federal (STF) ser\u00e1 respons\u00e1vel por decidir, no pr\u00f3ximo dia 25 de mar\u00e7o, se aceita a den\u00fancia apresentada pela Procuradoria-Geral da Rep\u00fablica (PGR) contra o ex-presidente Jair Bolsonaro e outros sete acusados de envolvimento em uma suposta tentativa de golpe de Estado em 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O grupo faz parte de um dos n\u00facleos apontados pela PGR como integrantes de uma organiza\u00e7\u00e3o criminosa voltada para ataques ao <a href=\"https:\/\/latamreports.com\/br\/pt-enfrenta-tensao-interna-sobre-sucessao-apesar-de-intervencao-de-lula\/\">Estado <\/a>Democr\u00e1tico de Direito. Ao todo, 34 pessoas foram denunciadas, divididas em cinco n\u00facleos distintos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caso a Primeira Turma do STF aceite a den\u00fancia, Bolsonaro e seus aliados se tornar\u00e3o r\u00e9us, dando in\u00edcio a uma a\u00e7\u00e3o penal no tribunal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Como funciona o julgamento na Primeira Turma do STF?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O STF \u00e9 composto por 11 ministros, divididos em duas Turmas, cada uma com cinco integrantes. O presidente da Corte, Lu\u00eds Roberto Barroso, n\u00e3o participa desses colegiados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A<strong> <\/strong>Primeira Turma, que julgar\u00e1 o caso de Bolsonaro, \u00e9 formada pelos ministros:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Cristiano Zanin<\/strong> (presidente)<\/li>\n\n\n\n<li><strong>Alexandre de Moraes<\/strong><\/li>\n\n\n\n<li><strong>Luiz Fux<\/strong><\/li>\n\n\n\n<li><strong>Fl\u00e1vio Dino<\/strong><\/li>\n\n\n\n<li><strong>C\u00e1rmen L\u00facia<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Essa divis\u00e3o permite que as Turmas julguem processos penais, incluindo a\u00e7\u00f5es contra autoridades p\u00fablicas, pedidos de liberdade de presos e recursos diversos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 2023, o STF alterou suas regras internas, devolvendo \u00e0s Turmas a compet\u00eancia para julgar investiga\u00e7\u00f5es criminais e processos que envolvem crimes. Como o relator do caso, ministro Alexandre de Moraes, pertence \u00e0 Primeira Turma, a decis\u00e3o sobre a den\u00fancia ficou sob responsabilidade desse colegiado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A decis\u00e3o da Primeira Turma ser\u00e1 um divisor de \u00e1guas no caso. Se os ministros rejeitarem a den\u00fancia da PGR, o processo ser\u00e1 arquivado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caso a den\u00fancia seja aceita, Bolsonaro e seus aliados se tornar\u00e3o r\u00e9us, e o caso avan\u00e7ar\u00e1 para a fase de instru\u00e7\u00e3o, onde ser\u00e3o coletadas provas e depoimentos. Somente ap\u00f3s essa etapa o STF decidir\u00e1 se os acusados ser\u00e3o absolvidos ou condenados. Se condenados, cada um poder\u00e1 receber uma pena espec\u00edfica, conforme sua participa\u00e7\u00e3o nos fatos investigados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quem s\u00e3o os ministros da Primeira Turma?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os cinco ministros que comp\u00f5em a Primeira Turma possuem trajet\u00f3rias distintas e j\u00e1 atuaram em diferentes \u00e1reas do Direito antes de chegarem ao STF. Confira um breve perfil de cada um:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Alexandre de Moraes<\/strong>: Ex-promotor de Justi\u00e7a em S\u00e3o Paulo, foi ministro da Justi\u00e7a no governo Michel Temer e presidente do TSE entre 2022 e 2024. Relator do caso, Moraes tem sido uma das figuras centrais no julgamento dos atos antidemocr\u00e1ticos de 2022.<\/li>\n\n\n\n<li><strong>Luiz Fux<\/strong>: Foi juiz de Direito e ministro do STJ antes de chegar ao STF. Presidiu a Corte de 2020 a 2022, sendo respons\u00e1vel por decis\u00f5es relevantes durante a pandemia da Covid-19.<\/li>\n\n\n\n<li><strong>Fl\u00e1vio Dino<\/strong>: Ex-juiz federal, deputado, governador do Maranh\u00e3o e ministro da Justi\u00e7a no governo Lula, assumiu uma vaga no STF em 2024.<\/li>\n\n\n\n<li><strong>C\u00e1rmen L\u00facia<\/strong>: Ex-procuradora do Estado de Minas Gerais, foi a primeira mulher a presidir o TSE e tamb\u00e9m comandou o STF entre 2016 e 2018.<\/li>\n\n\n\n<li><strong>Cristiano Zanin<\/strong>: Advogado especializado em lit\u00edgios estrat\u00e9gicos, ganhou notoriedade como defensor de Lula na Lava Jato antes de ser indicado ao STF.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">O julgamento do dia 25 de mar\u00e7o ser\u00e1 fundamental para definir os rumos da den\u00fancia. Se a Primeira Turma aceitar a acusa\u00e7\u00e3o da PGR, Bolsonaro e seus aliados ter\u00e3o que enfrentar um processo criminal no Supremo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acompanhe o <strong>LatAm Reports<\/strong> para mais atualiza\u00e7\u00f5es sobre o julgamento e seus <a href=\"https:\/\/latamreports.com\/br\/governo-subestima-gastos-com-previdencia-e-posterga-ajustes-no-orcamento\/\">desdobramentos<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Primeira Turma do Supremo Tribunal Federal (STF) ser\u00e1 respons\u00e1vel por decidir, no pr\u00f3ximo dia 25 de mar\u00e7o, se aceita a den\u00fancia apresentada pela Procuradoria-Geral &#8230; <a title=\"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro e aliados por tentativa de golpe\" class=\"read-more\" href=\"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/\" aria-label=\"Read more about STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro e aliados por tentativa de golpe\">Read more<\/a><\/p>\n","protected":false},"author":7,"featured_media":11164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[13],"tags":[31],"class_list":["post-11163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-brasil","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro<\/title>\n<meta name=\"description\" content=\"A Primeira Turma do Supremo Tribunal Federal (STF) ser\u00e1 respons\u00e1vel por decidir, no pr\u00f3ximo dia 25 de mar\u00e7o, se aceita a den\u00fancia...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro\" \/>\n<meta property=\"og:description\" content=\"A Primeira Turma do Supremo Tribunal Federal (STF) ser\u00e1 respons\u00e1vel por decidir, no pr\u00f3ximo dia 25 de mar\u00e7o, se aceita a den\u00fancia...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/\" \/>\n<meta property=\"og:site_name\" content=\"LatAm Reports\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/latamreports\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-14T17:43:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-14T17:43:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-26-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"LatAm Reports Redatores da Equipe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@latamreports\" \/>\n<meta name=\"twitter:site\" content=\"@latamreports\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"LatAm Reports Redatores da Equipe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\\\/\"},\"author\":{\"name\":\"LatAm Reports Redatores da Equipe\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/person\\\/a561f2de7e5ccabfab38d239b39fdb70\"},\"headline\":\"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro e aliados por tentativa de golpe\",\"datePublished\":\"2025-03-14T17:43:56+00:00\",\"dateModified\":\"2025-03-14T17:43:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\\\/\"},\"wordCount\":607,\"publisher\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/design-26-1.png\",\"keywords\":[\"Brasil\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\\\/\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\\\/\",\"name\":\"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/design-26-1.png\",\"datePublished\":\"2025-03-14T17:43:56+00:00\",\"dateModified\":\"2025-03-14T17:43:58+00:00\",\"description\":\"A Primeira Turma do Supremo Tribunal Federal (STF) ser\u00e1 respons\u00e1vel por decidir, no pr\u00f3ximo dia 25 de mar\u00e7o, se aceita a den\u00fancia...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/latamreports.com\\\/br\\\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/design-26-1.png\",\"contentUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/design-26-1.png\",\"width\":1200,\"height\":630,\"caption\":\"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro e aliados por tentativa de golpe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro e aliados por tentativa de golpe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\",\"name\":\"LatAm Reports\",\"description\":\"Not\u00edcias e opini\u00f5es de todas as Am\u00e9ricas\",\"publisher\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/latamreports.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#organization\",\"name\":\"LatAm Reports\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/cropped-PNG2.png\",\"contentUrl\":\"https:\\\/\\\/latamreports.com\\\/br\\\/wp-content\\\/uploads\\\/cropped-PNG2.png\",\"width\":2522,\"height\":1014,\"caption\":\"LatAm Reports\"},\"image\":{\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/latamreports\",\"https:\\\/\\\/x.com\\\/latamreports\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/latamreports.com\\\/br\\\/#\\\/schema\\\/person\\\/a561f2de7e5ccabfab38d239b39fdb70\",\"name\":\"LatAm Reports Redatores da Equipe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g\",\"caption\":\"LatAm Reports Redatores da Equipe\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro","description":"A Primeira Turma do Supremo Tribunal Federal (STF) ser\u00e1 respons\u00e1vel por decidir, no pr\u00f3ximo dia 25 de mar\u00e7o, se aceita a den\u00fancia...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/","og_locale":"en_US","og_type":"article","og_title":"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro","og_description":"A Primeira Turma do Supremo Tribunal Federal (STF) ser\u00e1 respons\u00e1vel por decidir, no pr\u00f3ximo dia 25 de mar\u00e7o, se aceita a den\u00fancia...","og_url":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/","og_site_name":"LatAm Reports","article_publisher":"https:\/\/facebook.com\/latamreports","article_published_time":"2025-03-14T17:43:56+00:00","article_modified_time":"2025-03-14T17:43:58+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-26-1.png","type":"image\/png"}],"author":"LatAm Reports Redatores da Equipe","twitter_card":"summary_large_image","twitter_creator":"@latamreports","twitter_site":"@latamreports","twitter_misc":{"Written by":"LatAm Reports Redatores da Equipe","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/#article","isPartOf":{"@id":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/"},"author":{"name":"LatAm Reports Redatores da Equipe","@id":"https:\/\/latamreports.com\/br\/#\/schema\/person\/a561f2de7e5ccabfab38d239b39fdb70"},"headline":"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro e aliados por tentativa de golpe","datePublished":"2025-03-14T17:43:56+00:00","dateModified":"2025-03-14T17:43:58+00:00","mainEntityOfPage":{"@id":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/"},"wordCount":607,"publisher":{"@id":"https:\/\/latamreports.com\/br\/#organization"},"image":{"@id":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/#primaryimage"},"thumbnailUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-26-1.png","keywords":["Brasil"],"articleSection":["Pol\u00edtica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/","url":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/","name":"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro","isPartOf":{"@id":"https:\/\/latamreports.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/#primaryimage"},"image":{"@id":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/#primaryimage"},"thumbnailUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-26-1.png","datePublished":"2025-03-14T17:43:56+00:00","dateModified":"2025-03-14T17:43:58+00:00","description":"A Primeira Turma do Supremo Tribunal Federal (STF) ser\u00e1 respons\u00e1vel por decidir, no pr\u00f3ximo dia 25 de mar\u00e7o, se aceita a den\u00fancia...","breadcrumb":{"@id":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/#primaryimage","url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-26-1.png","contentUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/design-26-1.png","width":1200,"height":630,"caption":"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro e aliados por tentativa de golpe"},{"@type":"BreadcrumbList","@id":"https:\/\/latamreports.com\/br\/stf-decide-em-marco-se-aceita-denuncia-contra-bolsonaro-e-aliados-por-tentativa-de-golpe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/latamreports.com\/br\/"},{"@type":"ListItem","position":2,"name":"STF decide em mar\u00e7o se aceita den\u00fancia contra Bolsonaro e aliados por tentativa de golpe"}]},{"@type":"WebSite","@id":"https:\/\/latamreports.com\/br\/#website","url":"https:\/\/latamreports.com\/br\/","name":"LatAm Reports","description":"Not\u00edcias e opini\u00f5es de todas as Am\u00e9ricas","publisher":{"@id":"https:\/\/latamreports.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latamreports.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/latamreports.com\/br\/#organization","name":"LatAm Reports","url":"https:\/\/latamreports.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/latamreports.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/cropped-PNG2.png","contentUrl":"https:\/\/latamreports.com\/br\/wp-content\/uploads\/cropped-PNG2.png","width":2522,"height":1014,"caption":"LatAm Reports"},"image":{"@id":"https:\/\/latamreports.com\/br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/latamreports","https:\/\/x.com\/latamreports"]},{"@type":"Person","@id":"https:\/\/latamreports.com\/br\/#\/schema\/person\/a561f2de7e5ccabfab38d239b39fdb70","name":"LatAm Reports Redatores da Equipe","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/842c5b7841c51c2ca298240a3fecd7dba9b83df829ac90c1e68c81c6fc158eee?s=96&d=mm&r=g","caption":"LatAm Reports Redatores da Equipe"}}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/11163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/comments?post=11163"}],"version-history":[{"count":1,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/11163\/revisions"}],"predecessor-version":[{"id":11165,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/posts\/11163\/revisions\/11165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/media\/11164"}],"wp:attachment":[{"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/media?parent=11163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/categories?post=11163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latamreports.com\/br\/wp-json\/wp\/v2\/tags?post=11163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}